{"id":2982,"date":"2024-07-19T07:30:46","date_gmt":"2024-07-19T07:30:46","guid":{"rendered":"https:\/\/qsddoorlock.com\/?post_type=product&#038;p=2982"},"modified":"2024-07-19T07:31:36","modified_gmt":"2024-07-19T07:31:36","slug":"smart-lock-c7d","status":"publish","type":"product","link":"https:\/\/qsddoorlock.com\/fr\/product\/smart-lock-c7d\/","title":{"rendered":"Smart Lock: C7D"},"content":{"rendered":"\n<figure class=\"wp-block-video\"><video controls src=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/C6D\u5f00\u7bb1_\u65e0logo.mp4\"><\/video><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Model No.: C7D<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>TECHNICAL SPECIFICATION:&nbsp;<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Material<\/td><td>Aluminum alloy<\/td><\/tr><tr><td>Available color<\/td><td>Black<\/td><\/tr><tr><td>Panel Sizes<\/td><td>L 158(mm)*W 26(mm)<\/td><\/tr><tr><td>Unlock method<\/td><td>App, Fingerprint, Pass code, RFID Card, Manual key<\/td><\/tr><tr><td>App name<\/td><td>TTlock \/ TThotel APP &amp; Tuya \/ Smart Life APP<\/td><\/tr><tr><td>Power supply<\/td><td>DC6V, 4pcs alkaline batteries<\/td><\/tr><tr><td>Battery life<\/td><td>Bluetooth&nbsp;TTlock Smart Lock( 12 months) Bluetooth Tuya Smart Lock( 12&nbsp;months)<\/td><\/tr><tr><td>Mortise<\/td><td>5845,4585,5085,6085,7255,7260 Mortise options<\/td><\/tr><tr><td>Cylinder<\/td><td>C-level Cylinder<\/td><\/tr><tr><td>Door Type<\/td><td>Wood door, Steel door, Stainless Steel door, Aluminum door<\/td><\/tr><tr><td>Door thickness<\/td><td>35-50mm<\/td><\/tr><tr><td>Working temperature<\/td><td>-20- + 55\u2103<\/td><\/tr><tr><td>Working humidity<\/td><td>20-95% RH<\/td><\/tr><tr><td>Card reading distance<\/td><td>0-5cm<\/td><\/tr><tr><td>Reading &amp; writing time<\/td><td>&lt;1s<\/td><\/tr><tr><td>Date keeping<\/td><td>Over 10 years<\/td><\/tr><tr><td>Reading &amp; writing way<\/td><td>Non-touched closer induction<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-masonry.kb-gallery-id-2982_3f656e-00{margin:-5px;}.kb-gallery-type-masonry.kb-gallery-id-2982_3f656e-00 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-2982_3f656e-00 .kadence-blocks-gallery-item .kb-gal-image-radius{border-radius:0px 0px 0px 0px;}<\/style><div class=\"kb-gallery-wrap-id-2982_3f656e-00 alignleft alignleft wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-masonry kb-masonry-init kb-gallery-id-2982_3f656e-00 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"1\" data-columns-xl=\"1\" data-columns-md=\"1\" data-columns-sm=\"1\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:750px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:134%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.0-10.png\" width=\"750\" height=\"1012\" alt=\"\" data-full-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.0-10.png\" data-light-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.0-10.png\" data-id=\"2987\" class=\"wp-image-2987\" srcset=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.0-10.png 750w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.0-10-222x300.png 222w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:960px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:100%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.2-35.png\" width=\"960\" height=\"960\" alt=\"\" data-full-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.2-35.png\" data-light-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.2-35.png\" data-id=\"2988\" class=\"wp-image-2988\" srcset=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.2-35.png 960w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.2-35-300x300.png 300w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.2-35-150x150.png 150w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.2-35-768x768.png 768w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.2-35-450x450.png 450w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.2-35-800x800.png 800w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1.2-35-100x100.png 100w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:750px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:106%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1\u56db\u79cd\u5f00\u9501\u65b9\u5f0f-21.png\" width=\"750\" height=\"796\" alt=\"\" data-full-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1\u56db\u79cd\u5f00\u9501\u65b9\u5f0f-21.png\" data-light-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1\u56db\u79cd\u5f00\u9501\u65b9\u5f0f-21.png\" data-id=\"2989\" class=\"wp-image-2989\" srcset=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1\u56db\u79cd\u5f00\u9501\u65b9\u5f0f-21.png 750w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/1\u56db\u79cd\u5f00\u9501\u65b9\u5f0f-21-283x300.png 283w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:679px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:150%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3.1-TTLOCK-\u6d41\u7a0b\u56fe-10-679x1024.png\" width=\"679\" height=\"1024\" alt=\"\" data-full-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3.1-TTLOCK-\u6d41\u7a0b\u56fe-10.png\" data-light-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3.1-TTLOCK-\u6d41\u7a0b\u56fe-10.png\" data-id=\"2990\" class=\"wp-image-2990\" srcset=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3.1-TTLOCK-\u6d41\u7a0b\u56fe-10-679x1024.png 679w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3.1-TTLOCK-\u6d41\u7a0b\u56fe-10-199x300.png 199w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3.1-TTLOCK-\u6d41\u7a0b\u56fe-10.png 750w\" sizes=\"(max-width: 679px) 100vw, 679px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:631px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:162%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3.3-TUYA-\u6d41\u7a0b\u56fe-16-631x1024.png\" width=\"631\" height=\"1024\" alt=\"\" data-full-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3.3-TUYA-\u6d41\u7a0b\u56fe-16.png\" data-light-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3.3-TUYA-\u6d41\u7a0b\u56fe-16.png\" data-id=\"2991\" class=\"wp-image-2991\" srcset=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3.3-TUYA-\u6d41\u7a0b\u56fe-16-631x1024.png 631w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3.3-TUYA-\u6d41\u7a0b\u56fe-16-185x300.png 185w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3.3-TUYA-\u6d41\u7a0b\u56fe-16.png 750w\" sizes=\"(max-width: 631px) 100vw, 631px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:790px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:100%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3-3.png\" width=\"790\" height=\"790\" alt=\"\" data-full-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3-3.png\" data-light-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3-3.png\" data-id=\"2992\" class=\"wp-image-2992\" srcset=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3-3.png 790w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3-3-300x300.png 300w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3-3-150x150.png 150w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3-3-768x768.png 768w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3-3-450x450.png 450w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/3-3-100x100.png 100w\" sizes=\"(max-width: 790px) 100vw, 790px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:790px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:100%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5-4.png\" width=\"790\" height=\"790\" alt=\"\" data-full-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5-4.png\" data-light-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5-4.png\" data-id=\"2985\" class=\"wp-image-2985\" srcset=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5-4.png 790w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5-4-300x300.png 300w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5-4-150x150.png 150w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5-4-768x768.png 768w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5-4-450x450.png 450w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5-4-100x100.png 100w\" sizes=\"(max-width: 790px) 100vw, 790px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:639px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:160%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/\u9501\u4f53-2-639x1024.png\" width=\"639\" height=\"1024\" alt=\"\" data-full-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/\u9501\u4f53-2.png\" data-light-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/\u9501\u4f53-2.png\" data-id=\"2986\" class=\"wp-image-2986\" srcset=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/\u9501\u4f53-2-639x1024.png 639w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/\u9501\u4f53-2-187x300.png 187w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/\u9501\u4f53-2.png 750w\" sizes=\"(max-width: 639px) 100vw, 639px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\" style=\"max-width:700px;\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic\" style=\"padding-bottom:146%;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5.0-5-700x1024.png\" width=\"700\" height=\"1024\" alt=\"\" data-full-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5.0-5.png\" data-light-image=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5.0-5.png\" data-id=\"2984\" class=\"wp-image-2984\" srcset=\"https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5.0-5-700x1024.png 700w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5.0-5-205x300.png 205w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5.0-5-768x1123.png 768w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5.0-5-800x1170.png 800w, https:\/\/qsddoorlock.com\/wp-content\/uploads\/2024\/07\/5.0-5.png 960w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/figure><\/div><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<ul>\n<li>Including App,Fingerprint,Code,Card and Manual Key funtions<\/li>\n<li>Zinc Alloy Material<\/li>\n<li>5845,4585, 5085, 6085,7255,7060 Mortise Options<\/li>\n<\/ul>\n","protected":false},"featured_media":2993,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"product_cat":[15,45],"product_tag":[],"translation":{"provider":"WPGlobus","version":"2.12.0","language":"fr","enabled_languages":["en","ar","zh","nl","fr","de","hi","id","it","ja","ko","pt","ru","es","th","tr","vi"],"languages":{"en":{"title":true,"content":true,"excerpt":true},"ar":{"title":false,"content":false,"excerpt":false},"zh":{"title":false,"content":false,"excerpt":false},"nl":{"title":false,"content":false,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"de":{"title":false,"content":false,"excerpt":false},"hi":{"title":false,"content":false,"excerpt":false},"id":{"title":false,"content":false,"excerpt":false},"it":{"title":false,"content":false,"excerpt":false},"ja":{"title":false,"content":false,"excerpt":false},"ko":{"title":false,"content":false,"excerpt":false},"pt":{"title":false,"content":false,"excerpt":false},"ru":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false},"th":{"title":false,"content":false,"excerpt":false},"tr":{"title":false,"content":false,"excerpt":false},"vi":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/qsddoorlock.com\/fr\/wp-json\/wp\/v2\/product\/2982"}],"collection":[{"href":"https:\/\/qsddoorlock.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/qsddoorlock.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/qsddoorlock.com\/fr\/wp-json\/wp\/v2\/comments?post=2982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qsddoorlock.com\/fr\/wp-json\/wp\/v2\/media\/2993"}],"wp:attachment":[{"href":"https:\/\/qsddoorlock.com\/fr\/wp-json\/wp\/v2\/media?parent=2982"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/qsddoorlock.com\/fr\/wp-json\/wp\/v2\/product_cat?post=2982"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/qsddoorlock.com\/fr\/wp-json\/wp\/v2\/product_tag?post=2982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}